{"id":12246,"date":"2024-03-19T14:58:27","date_gmt":"2024-03-19T14:58:27","guid":{"rendered":"https:\/\/cura-glass.nl\/projecten\/"},"modified":"2025-10-22T09:27:11","modified_gmt":"2025-10-22T09:27:11","slug":"projecten","status":"publish","type":"page","link":"https:\/\/cura-glass.nl\/de\/projecten\/","title":{"rendered":"Projecten"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-12246","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projecten - CURA Glass<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cura-glass.nl\/de\/projecten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projecten - CURA Glass\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cura-glass.nl\/de\/projecten\/\" \/>\n<meta property=\"og:site_name\" content=\"CURA Glass\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CURAGlass\/?locale=nl_NL\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T09:27:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/projecten\\\/\",\"url\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/projecten\\\/\",\"name\":\"Projecten - CURA Glass\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/#website\"},\"datePublished\":\"2024-03-19T14:58:27+00:00\",\"dateModified\":\"2025-10-22T09:27:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/projecten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cura-glass.nl\\\/de\\\/projecten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/projecten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projecten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/\",\"name\":\"CURA Glass\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/#organization\",\"name\":\"CURA Glass\",\"url\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cura-glass.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-cura-e1710861172170.png\",\"contentUrl\":\"https:\\\/\\\/cura-glass.nl\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-cura-e1710861172170.png\",\"width\":558,\"height\":250,\"caption\":\"CURA Glass\"},\"image\":{\"@id\":\"https:\\\/\\\/cura-glass.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CURAGlass\\\/?locale=nl_NL\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/curaglass\\\/?originalSubdomain=nl\",\"https:\\\/\\\/www.instagram.com\\\/curaglass\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projecten - CURA Glass","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cura-glass.nl\/de\/projecten\/","og_locale":"de_DE","og_type":"article","og_title":"Projecten - CURA Glass","og_url":"https:\/\/cura-glass.nl\/de\/projecten\/","og_site_name":"CURA Glass","article_publisher":"https:\/\/www.facebook.com\/CURAGlass\/?locale=nl_NL","article_modified_time":"2025-10-22T09:27:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cura-glass.nl\/de\/projecten\/","url":"https:\/\/cura-glass.nl\/de\/projecten\/","name":"Projecten - CURA Glass","isPartOf":{"@id":"https:\/\/cura-glass.nl\/de\/#website"},"datePublished":"2024-03-19T14:58:27+00:00","dateModified":"2025-10-22T09:27:11+00:00","breadcrumb":{"@id":"https:\/\/cura-glass.nl\/de\/projecten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cura-glass.nl\/de\/projecten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cura-glass.nl\/de\/projecten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cura-glass.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Projecten"}]},{"@type":"WebSite","@id":"https:\/\/cura-glass.nl\/de\/#website","url":"https:\/\/cura-glass.nl\/de\/","name":"CURA Glass","description":"","publisher":{"@id":"https:\/\/cura-glass.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cura-glass.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cura-glass.nl\/de\/#organization","name":"CURA Glass","url":"https:\/\/cura-glass.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cura-glass.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/cura-glass.nl\/wp-content\/uploads\/2024\/03\/logo-cura-e1710861172170.png","contentUrl":"https:\/\/cura-glass.nl\/wp-content\/uploads\/2024\/03\/logo-cura-e1710861172170.png","width":558,"height":250,"caption":"CURA Glass"},"image":{"@id":"https:\/\/cura-glass.nl\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CURAGlass\/?locale=nl_NL","https:\/\/www.linkedin.com\/company\/curaglass\/?originalSubdomain=nl","https:\/\/www.instagram.com\/curaglass\/"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/pages\/12246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/comments?post=12246"}],"version-history":[{"count":6,"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/pages\/12246\/revisions"}],"predecessor-version":[{"id":19439,"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/pages\/12246\/revisions\/19439"}],"wp:attachment":[{"href":"https:\/\/cura-glass.nl\/de\/wp-json\/wp\/v2\/media?parent=12246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}